{"id":100,"count":1,"description":"","link":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/","name":"SAP: joins","slug":"sap-joins","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SAP: joins Archives - Esfoor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAP: joins Archives - Esfoor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/\" \/>\n<meta property=\"og:site_name\" content=\"Esfoor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/tag\\\/sap-joins\\\/\",\"url\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/tag\\\/sap-joins\\\/\",\"name\":\"SAP: joins Archives - Esfoor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/tag\\\/sap-joins\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/tag\\\/sap-joins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAP: joins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/\",\"name\":\"Esfoor\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esfoor.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAP: joins Archives - Esfoor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/","og_locale":"en_US","og_type":"article","og_title":"SAP: joins Archives - Esfoor","og_url":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/","og_site_name":"Esfoor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/","url":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/","name":"SAP: joins Archives - Esfoor","isPartOf":{"@id":"https:\/\/www.esfoor.fi\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.esfoor.fi\/en\/tag\/sap-joins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.esfoor.fi\/en\/"},{"@type":"ListItem","position":2,"name":"SAP: joins"}]},{"@type":"WebSite","@id":"https:\/\/www.esfoor.fi\/en\/#website","url":"https:\/\/www.esfoor.fi\/en\/","name":"Esfoor","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esfoor.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.esfoor.fi\/en\/wp-json\/wp\/v2\/tags\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esfoor.fi\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.esfoor.fi\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.esfoor.fi\/en\/wp-json\/wp\/v2\/posts?tags=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}